{"id":1,"count":72,"description":"Travel tips for travellers ","link":"https:\/\/fontegaiatour.it\/en\/blog\/category\/travel-tips\/","name":"Travel Tips","slug":"travel-tips","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/fontegaiatour.it\/en\/blog\/wp-json\/wp\/v2\/categories\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fontegaiatour.it\/en\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/fontegaiatour.it\/en\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/fontegaiatour.it\/en\/blog\/wp-json\/wp\/v2\/posts?categories=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}